{"id":5183,"date":"2020-05-05T04:03:05","date_gmt":"2020-05-05T04:03:05","guid":{"rendered":"http:\/\/asartorialsuit.com\/shop-online\/shop\/import-placeholder-for-844\/"},"modified":"2020-06-14T12:55:43","modified_gmt":"2020-06-14T12:55:43","slug":"36180-1102-2","status":"publish","type":"product","link":"http:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/","title":{"rendered":"36180-1102"},"content":{"rendered":"<p>Fabric: Cotton CVC<\/p>\n<p>Pattern: Check<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fabric: Cotton CVC<\/p>\n<p>Pattern: Check<\/p>\n","protected":false},"featured_media":775,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[204,22],"product_tag":[27,83,79,76,84,35,33,78],"class_list":{"0":"post-5183","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-all-shirts","7":"product_cat-shirts","8":"product_tag-bespoke","9":"product_tag-dress-shirts","10":"product_tag-fitted-shirts","11":"product_tag-handmade","12":"product_tag-plain-shirts","13":"product_tag-shirts","14":"product_tag-tailor-made-shirts","15":"product_tag-tailored-shirt","17":"first","18":"instock","19":"sale","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>36180-1102 - A Sartorial Suit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"36180-1102 - A Sartorial Suit\" \/>\n<meta property=\"og:description\" content=\"Fabric: Cotton CVC  Pattern: Check\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/\" \/>\n<meta property=\"og:site_name\" content=\"A Sartorial Suit\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-14T12:55:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/\",\"url\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/\",\"name\":\"36180-1102 - A Sartorial Suit\",\"isPartOf\":{\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg\",\"datePublished\":\"2020-05-05T04:03:05+00:00\",\"dateModified\":\"2020-06-14T12:55:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#primaryimage\",\"url\":\"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg\",\"contentUrl\":\"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/asartorialsuit.com\/shop-online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop Online\",\"item\":\"https:\/\/asartorialsuit.com\/shop-online\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"36180-1102\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/#website\",\"url\":\"https:\/\/asartorialsuit.com\/shop-online\/\",\"name\":\"A Sartorial Suit\",\"description\":\"Online Store for Custom Suits and Shirts\",\"publisher\":{\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/asartorialsuit.com\/shop-online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/#organization\",\"name\":\"A Sartorial Suit\",\"url\":\"https:\/\/asartorialsuit.com\/shop-online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/Favicon.png\",\"contentUrl\":\"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"A Sartorial Suit\"},\"image\":{\"@id\":\"https:\/\/asartorialsuit.com\/shop-online\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"36180-1102 - A Sartorial Suit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/","og_locale":"en_US","og_type":"article","og_title":"36180-1102 - A Sartorial Suit","og_description":"Fabric: Cotton CVC  Pattern: Check","og_url":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/","og_site_name":"A Sartorial Suit","article_modified_time":"2020-06-14T12:55:43+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/","url":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/","name":"36180-1102 - A Sartorial Suit","isPartOf":{"@id":"https:\/\/asartorialsuit.com\/shop-online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#primaryimage"},"image":{"@id":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#primaryimage"},"thumbnailUrl":"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg","datePublished":"2020-05-05T04:03:05+00:00","dateModified":"2020-06-14T12:55:43+00:00","breadcrumb":{"@id":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#primaryimage","url":"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg","contentUrl":"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/KB36180-36N.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/asartorialsuit.com\/shop-online\/shop\/shirts\/all-shirts\/36180-1102-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/asartorialsuit.com\/shop-online\/"},{"@type":"ListItem","position":2,"name":"Shop Online","item":"https:\/\/asartorialsuit.com\/shop-online\/shop\/"},{"@type":"ListItem","position":3,"name":"36180-1102"}]},{"@type":"WebSite","@id":"https:\/\/asartorialsuit.com\/shop-online\/#website","url":"https:\/\/asartorialsuit.com\/shop-online\/","name":"A Sartorial Suit","description":"Online Store for Custom Suits and Shirts","publisher":{"@id":"https:\/\/asartorialsuit.com\/shop-online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asartorialsuit.com\/shop-online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/asartorialsuit.com\/shop-online\/#organization","name":"A Sartorial Suit","url":"https:\/\/asartorialsuit.com\/shop-online\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/asartorialsuit.com\/shop-online\/#\/schema\/logo\/image\/","url":"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/Favicon.png","contentUrl":"http:\/\/asartorialsuit.com\/shop-online\/wp-content\/uploads\/2020\/04\/Favicon.png","width":512,"height":512,"caption":"A Sartorial Suit"},"image":{"@id":"https:\/\/asartorialsuit.com\/shop-online\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product\/5183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/comments?post=5183"}],"version-history":[{"count":1,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product\/5183\/revisions"}],"predecessor-version":[{"id":5708,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product\/5183\/revisions\/5708"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/media\/775"}],"wp:attachment":[{"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/media?parent=5183"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product_brand?post=5183"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product_cat?post=5183"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/asartorialsuit.com\/shop-online\/wp-json\/wp\/v2\/product_tag?post=5183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}